{"id":43943,"date":"2022-11-29T17:43:22","date_gmt":"2022-11-29T17:43:22","guid":{"rendered":"https:\/\/jobs.cagi.ch\/?post_type=job_listing&#038;p=43943"},"modified":"2022-12-16T00:41:30","modified_gmt":"2022-12-16T00:41:30","slug":"fondation-apprentis-dauteuil-international-faai-geneva-internship-stagiaire-marketing-et-communication-2","status":"expired","type":"job_listing","link":"https:\/\/jobs.cagi.ch\/fr\/?post_type=job_listing&p=43943","title":{"rendered":"Stagiaire Marketing et Communication"},"content":{"rendered":"<p>Fondation Apprentis d&rsquo;Auteuil International (FAAI)<\/p>\n","protected":false},"author":111,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","job_listing_type":[75],"job_listing_category":[36],"job_listing_location":[90],"job_listing_tag":[],"class_list":["post-43943","job_listing","type-job_listing","status-expired","hentry","job_listing_type-internship","job_listing_category-communication","job_listing_location-geneva"],"metas":{"job-description":"La d\u00e9tresse d\u2019une part grandissante de la jeunesse est la plus grande injustice de notre \u00e9poque. Pour beaucoup, les jeunes sont devenus un probl\u00e8me de soci\u00e9t\u00e9 alors qu\u2019ils devraient en \u00eatre la plus grande richesse.\r\n\r\nLa Fondation Apprentis d\u2019Auteuil International (FAAI) est une <strong>Fondation reconnue d\u2019utilit\u00e9 publique<\/strong> cr\u00e9\u00e9e en 2013, qui soutient les <strong>projets internationaux<\/strong> de la Fondation d\u2019Auteuil (cr\u00e9\u00e9e en 1866), en <strong>partenariat avec des acteurs locaux<\/strong>. Ces activit\u00e9s internationales s\u2019articulent autour de quatre th\u00e9matiques : la <strong>protection des enfants<\/strong> en situation de rue, <strong>l\u2019accompagnement des familles<\/strong>, <strong>l\u2019entrepreneuriat et l\u2019insertion<\/strong>, et l\u2019ouverture au monde.\r\n\r\nLa FAAI porte \u00e9galement un <strong>plaidoyer en faveur des droits de l\u2019enfant<\/strong> aupr\u00e8s des institutions onusiennes, \u00e0 Gen\u00e8ve. Enfin, elle d\u00e9veloppe des projets <strong>d\u2019accompagnement scolaire et d\u2019insertion<\/strong>, en Suisse, en faveur des jeunes en difficult\u00e9 et en <strong>d\u00e9crochage scolaire<\/strong>.\r\n\r\n&nbsp;\r\n\r\nLe\/la titulaire de ce poste reporte \u00e0 la responsable de communication et \u00e0 la charg\u00e9e de plaidoyer international et travaillera en \u00e9troite collaboration avec le reste de l\u2019\u00e9quipe.\r\n<h3><strong>T\u00e2ches et responsabilit\u00e9s<\/strong><\/h3>\r\n<ul>\r\n \t<li>Coordonner la r\u00e9daction du rapport annuel 2022 en collaboration avec les chefs de projets, la responsable communication et la charg\u00e9e de plaidoyer international\u00a0;<\/li>\r\n \t<li>Soutenir le d\u00e9veloppement de la communication externe de la FAAI, en particulier en r\u00e9digeant des articles pour le site web\u00a0et\/ou les m\u00e9dias sociaux ;<\/li>\r\n \t<li>Animer et d\u00e9velopper les r\u00e9seaux sociaux en produisant du mat\u00e9riel visuel (twitter, instagram, linkedIn)\u00a0;<\/li>\r\n \t<li>Tenue du calendrier \u00e9ditorial\u00a0;<\/li>\r\n \t<li>Soutien \u00e0 la mise \u00e0 jour du site internet\u00a0;<\/li>\r\n \t<li>Assister la charg\u00e9e de plaidoyer international dans la pr\u00e9paration et la mise en page de supports de communication\u00a0;<\/li>\r\n \t<li>Traduction de certains documents\/articles en Anglais.<\/li>\r\n<\/ul>\r\nLe\/la titulaire du poste peut \u00eatre amen\u00e9(e) \u00e0 accomplir d\u2019autres t\u00e2ches selon le besoin.\r\n<h4><strong>Profil du poste<\/strong><\/h4>\r\n<ul>\r\n \t<li><strong>Etudiant(e) en cours de formation<\/strong> bachelor et\/ou master, id\u00e9alement en relations internationales, science politique ou sciences sociales, marketing, communication\u00a0;<\/li>\r\n \t<li>Il\/elle est flexible dans l\u2019accomplissement des t\u00e2ches incombant \u00e0 un bureau de petite taille (7-8 personnes)\u00a0;<\/li>\r\n \t<li>Le\/la titulaire est bien organis\u00e9(e), capable de travailler de fa\u00e7on autonome, aisance dans le r\u00e9dactionnel et la communication en g\u00e9n\u00e9ral, proactif\u00a0;<\/li>\r\n \t<li>Langues requises : fran\u00e7ais (tr\u00e8s bon niveau\/ou langue maternelle), une excellente ma\u00eetrise de l\u2019anglais parl\u00e9 et \u00e9crit\u00a0;<\/li>\r\n \t<li>Ma\u00eetrise des r\u00e9seaux sociaux\u00a0;<\/li>\r\n \t<li>Ma\u00eetrise d\u2019un ou plusieurs outils de cr\u00e9ation graphique, un atout\u00a0;<\/li>\r\n \t<li>Une exp\u00e9rience \/ connaissance de l\u2019environnement ONG en Suisse est un atout\u00a0;<\/li>\r\n \t<li>Nous offrons une opportunit\u00e9 de faire partie d\u2019une organisation\/\u00e9quipe dynamique et motiv\u00e9e qui contribue \u00e0 r\u00e9ins\u00e9rer la jeunesse en difficult\u00e9 pour lui donner un avenir meilleur.<\/li>\r\n<\/ul>\r\n<h4><strong>\u00a0<\/strong><strong>Conditions<\/strong><\/h4>\r\n<ul>\r\n \t<li>Le poste de stagiaire est \u00e0 100 %, pour une p\u00e9riode de 6 mois, bas\u00e9 \u00e0 Gen\u00e8ve<\/li>\r\n \t<li>Le poste comprend une indemnit\u00e9 mensuelle<\/li>\r\n \t<li>Date d\u2019entr\u00e9e en fonction souhait\u00e9e\u00a0: au plus t\u00f4t<\/li>\r\n \t<li>Les candidatures (<strong><u>CV et lettre de motivation<\/u><\/strong>) doivent \u00eatre envoy\u00e9es d\u2019ici le <strong>15 d\u00e9cembre 2022<\/strong> \u00e0 Laurence Triouleyre (<a href=\"mailto:laurence.triouleyre@apprentis-auteuil.org\">triouleyre@apprentis-auteuil.org<\/a>)<\/li>\r\n<\/ul>","_job_category":{"36":"Communication"},"organization-type":"NGO \/ ONG","fields-of-action":"Human Rights \/ Droits humains","_job_type":{"75":"Internship \/ Stage"},"_job_apply_type":"with_email","_job_apply_email":"","_job_apply_url":"","activity-rate":"100%","_job_salary_type":"","_job_salary":"","_job_experience":"","_job_application_deadline_date":"2022-12-15","_job_location":{"90":"Gen\u00e8ve"},"_job_logo":"https:\/\/jobs.cagi.ch\/wp-content\/uploads\/Logo-FAAI-150x150.png","_job_employer_name":"Fondation Apprentis d&rsquo;Auteuil International (FAAI)","_job_employer_url":"https:\/\/jobs.cagi.ch\/fr\/employer\/fondation-apprentis-dauteuil-international-faai\/"},"_links":{"self":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/43943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/comments?post=43943"}],"version-history":[{"count":2,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/43943\/revisions"}],"predecessor-version":[{"id":44057,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/43943\/revisions\/44057"}],"wp:attachment":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/media?parent=43943"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_type?post=43943"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_category?post=43943"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_location?post=43943"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=43943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}