{"id":94293,"date":"2024-06-10T13:22:18","date_gmt":"2024-06-10T13:22:18","guid":{"rendered":"https:\/\/jobs.cagi.ch\/?post_type=job_listing&#038;p=94293"},"modified":"2024-08-02T18:25:05","modified_gmt":"2024-08-02T18:25:05","slug":"fondation-eduki-geneva-internship-assistant%c2%b7e-de-projets-et-de-communication-2","status":"expired","type":"job_listing","link":"https:\/\/jobs.cagi.ch\/fr\/?post_type=job_listing&p=94293","title":{"rendered":"Assistant\u00b7e de projets et de communication"},"content":{"rendered":"<p>Fondation Eduki<\/p>\n","protected":false},"author":504,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","job_listing_type":[75],"job_listing_category":[36],"job_listing_location":[90],"job_listing_tag":[],"class_list":["post-94293","job_listing","type-job_listing","status-expired","hentry","job_listing_type-internship","job_listing_category-communication","job_listing_location-geneva"],"metas":{"job-description":"La Fondation Eduki a pour but de promouvoir l\u2019\u00e9ducation et la sensibilisation des jeunes au travail des organisations internationales et \u00e0 la coop\u00e9ration internationale. Elle vise ainsi \u00e0 conforterla vocation internationale de la Suisse et contribue \u00e0 tisser un lien durable entre les organisations internationales et les jeunes. Nos activit\u00e9s consistent notamment \u00e0 organiser des visites et des activit\u00e9s pour les jeunes, un concours national ou encore \u00e0 constituer des dossiers\r\nth\u00e9matiques.\r\n\r\nPour compl\u00e9ter notre \u00e9quipe, nous recherchons une personne proactive, avec un bon sens de l\u2019organisation et un esprit d\u2019\u00e9quipe, et ayant un fort int\u00e9r\u00eat pour la p\u00e9dagogie et les relations internationales.\r\n<h3>Activit\u00e9s principales :<\/h3>\r\n<ul>\r\n \t<li>Actualisation, d\u00e9veloppement de l\u2019information et assistance dans la mise en ligne de contenus p\u00e9dagogiques et interactifs sur le site Internet <a href=\"http:\/\/www.eduki.ch\">www.eduki.ch<\/a>\u00a0 \u00a0 \u00a0(Drupal 9 pour l'instant).<\/li>\r\n \t<li>R\u00e9daction de contenus, cr\u00e9ation de visuels et soutien pour les m\u00e9dias sociaux (FB, Instagram, X, LinkedIn).<\/li>\r\n \t<li>Cr\u00e9ation de contenus m\u00e9dia (vid\u00e9o, audio) et graphiques (Indesign, Illustrator).<\/li>\r\n \t<li>Selonlesbesoins du projet informatique de migration desdonn\u00e9es, assister aux processus.<\/li>\r\n \t<li>Assistance aux t\u00e2ches administratives telles que la gestion de l\u2019archive photo (Lightroom),<\/li>\r\n \t<li>l\u2019actualisation de la base de donn\u00e9es de contacts (FileMaker), et des traductions.<\/li>\r\n<\/ul>\r\n<h4>Profil :<\/h4>\r\n<ul>\r\n \t<li>En cours de formation universitaire (relations internationales, communication, sciences de l\u2019\u00e9ducation ou sociales).<\/li>\r\n \t<li>Excellentes capacit\u00e9s r\u00e9dactionnelles en fran\u00e7ais.<\/li>\r\n \t<li>Bonnes connaissances des logiciels de bureautique usuels (Word, Excel) et d\u2019outils de communication (m\u00e9dias sociaux).<\/li>\r\n \t<li>Bon sens de l\u2019organisation, excellente communication, personne dynamique et motiv\u00e9e.<\/li>\r\n \t<li>Sens de l\u2019autonomie et du travail en \u00e9quipe.<\/li>\r\n \t<li>Notions de la suite Creative d\u2019Adobe (Premiere pro, Photoshop, Lightroom, InDesign) ou\r\n\u00e9quivalent un atout (p.ex Canva).<\/li>\r\n \t<li>Un int\u00e9r\u00eat pour la Gen\u00e8ve internationale, la coop\u00e9ration internationale et le d\u00e9veloppement durable (assister dans les visites organis\u00e9es)<\/li>\r\n<\/ul>\r\nLangues :\r\n<ul>\r\n \t<li>Fran\u00e7ais : parfaite ma\u00eetrise \u00e0 l\u2019oral et \u00e0 l\u2019\u00e9crit<\/li>\r\n \t<li>Anglais, italien et\/ou allemand : Bonnes connaissances, un atout.<\/li>\r\n<\/ul>\r\nCette annonce s\u2019adresse uniquement aux \u00e9tudiant\u00b7e\u00b7s en cours de formation (Bachelor ou Master universitaire). La signature d\u2019une convention de stage (intra-cursus) et la validation du stage par l\u2019attribution de cr\u00e9dits d\u2019\u00e9tudes sont obligatoires.\r\n<ul>\r\n \t<li>Dur\u00e9e du stage : 6 mois, d\u00e8s le 12 ao\u00fbt ou \u00e0 convenir.<\/li>\r\n \t<li>Conditions : Taux de travail de 80%. D\u00e9fraiement mensuel brut de CHF 1\u2019700 (\u00e9quivalent 100%). Lieu de travail : Route de Ferney 106, 1202 Gen\u00e8ve<\/li>\r\n \t<li>Candidature : Veuillez envoyer un dossier de candidature complet comprenant une lettre de motivation ainsi qu\u2019un CV \u00e0 <a href=\"mailto:info@eduki.ch\">info@eduki.ch<\/a><\/li>\r\n<\/ul>","_job_category":{"36":"Communication"},"organization-type":"","fields-of-action":"Other \/ Autre","_job_type":{"75":"Internship \/ Stage"},"_job_apply_type":"with_email","_job_apply_email":"info@eduki.ch","_job_apply_url":"","activity-rate":"80%","_job_salary_type":"monthly","_job_salary":"CHF 1360 \/ mois","_job_experience":"0-2 years","_job_application_deadline_date":"2024-08-02","_job_location":{"90":"Gen\u00e8ve"},"_job_logo":"https:\/\/jobs.cagi.ch\/wp-content\/uploads\/Logo-Eduki-150x150.png","_job_employer_name":"Fondation Eduki","_job_employer_url":"https:\/\/jobs.cagi.ch\/employer\/fondation-eduki\/"},"_links":{"self":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/94293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/users\/504"}],"replies":[{"embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/comments?post=94293"}],"version-history":[{"count":1,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/94293\/revisions"}],"predecessor-version":[{"id":94295,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing\/94293\/revisions\/94295"}],"wp:attachment":[{"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/media?parent=94293"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_type?post=94293"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_category?post=94293"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_location?post=94293"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/jobs.cagi.ch\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=94293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}